{"id":258,"date":"2024-03-28T11:13:32","date_gmt":"2024-03-28T02:13:32","guid":{"rendered":"https:\/\/e-kanagawa.co.jp\/en\/?page_id=258"},"modified":"2024-06-28T17:08:39","modified_gmt":"2024-06-28T08:08:39","slug":"m_p_p","status":"publish","type":"page","link":"https:\/\/e-kanagawa.co.jp\/en\/m_p_p\/","title":{"rendered":"Materials &amp; Parts for Primary Batteries"},"content":{"rendered":"\n<div class=\"swell-block-fullWide pc-py-0 sp-py-0 alignfull b1-gp-back\"><div class=\"swell-block-fullWide__inner l-article\">\n<div class=\"wp-block-group gp-gr\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Materials &amp; Parts for Primary (Non-rechargeable) Batteries<\/h2>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"swell-block-fullWide pc-py-0 sp-py-40 alignfull b1-ft-back\"><div class=\"swell-block-fullWide__inner l-article\">\n<div class=\"swell-block-fullWide pc-py-20 sp-py-20 alignfull c5-ft-container\"><div class=\"swell-block-fullWide__inner\">\n<div class=\"swell-block-columns bbox\" style=\"--swl-clmn-mrgn--x:2rem\"><div class=\"swell-block-columns__inner\">\n<div class=\"swell-block-column swl-has-mb--s col\" style=\"--clmn-w--pc:30%\">\n<figure class=\"wp-block-image size-full c5-img u-lb-off u-mb-ctrl u-mb-20\"><img decoding=\"async\" width=\"340\" height=\"229\" src=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/zinc_carbon_battery.png\" alt=\"\" class=\"wp-image-1421\" srcset=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/zinc_carbon_battery.png 340w, https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/zinc_carbon_battery-300x202.png 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/figure>\n\n\n\n<p class=\"cap1\">Zinc Carbon Battery<\/p>\n\n\n\n<p class=\"cap2\">Data from &#8216;Battery Association of Japan&#8217;<\/p>\n<\/div>\n\n\n\n<div class=\"swell-block-column swl-has-mb--s col\" style=\"--clmn-w--pc:70%\">\n<div class=\"wp-block-group is-stack c5-text\">\n<h2 class=\"wp-block-heading\">Zinc Carbon Batteries(Cylindrical)<\/h2>\n\n\n\n<div class=\"swell-block-columns u-mb-ctrl u-mb-20\" style=\"--swl-clmn-mrgn--y:0px\"><div class=\"swell-block-columns__inner\">\n<div class=\"swell-block-column swl-has-mb--s col2\" style=\"--clmn-w--pc:50%\">\n<ul class=\"wp-block-list\">\n<li>Liner Paper<\/li>\n\n\n\n<li>Bottom Paper<\/li>\n\n\n\n<li>Black Card Paper<\/li>\n\n\n\n<li>Top Ring<\/li>\n\n\n\n<li>Bottom Ring<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"swell-block-column swl-has-mb--s col2\" style=\"--clmn-w--pc:50%\">\n<ul class=\"wp-block-list\">\n<li>Ammonium Chloride<\/li>\n\n\n\n<li>Zinc Oxide<\/li>\n\n\n\n<li>Wax<\/li>\n\n\n\n<li>Starch<\/li>\n\n\n\n<li>Shrink Film(PET, PO, PVC)<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Zinc Carbon Batteries 9V<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Microcrystaline Wax<\/li>\n\n\n\n<li>PVC Resin<\/li>\n\n\n\n<li>Stainless Steel(SUS430)<\/li>\n\n\n\n<li>Nickel Plated Steel Strip<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"swell-block-fullWide pc-py-20 sp-py-20 alignfull c5-ft-container\"><div class=\"swell-block-fullWide__inner\">\n<div class=\"swell-block-columns bbox\" style=\"--swl-clmn-mrgn--x:2rem\"><div class=\"swell-block-columns__inner\">\n<div class=\"swell-block-column swl-has-mb--s col\" style=\"--clmn-w--pc:30%\">\n<figure class=\"wp-block-image size-full c5-img u-lb-off u-mb-ctrl u-mb-20\"><img decoding=\"async\" width=\"340\" height=\"203\" src=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/alkaline_battery.png\" alt=\"\" class=\"wp-image-1440\" srcset=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/alkaline_battery.png 340w, https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/alkaline_battery-300x179.png 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/figure>\n\n\n\n<p class=\"cap1\">Alkaline Battery<\/p>\n\n\n\n<p class=\"cap2\">Data from &#8216;Battery Association of Japan&#8217;<\/p>\n<\/div>\n\n\n\n<div class=\"swell-block-column swl-has-mb--s col\" style=\"--clmn-w--pc:70%\">\n<div class=\"wp-block-group is-stack c5-text\">\n<h2 class=\"wp-block-heading\">Alkaline Batteries(Cylindrical)<\/h2>\n\n\n\n<ul class=\"u-mb-ctrl u-mb-20 wp-block-list\">\n<li>Zinc Powder<\/li>\n\n\n\n<li>Separator<\/li>\n\n\n\n<li>Gasket<\/li>\n\n\n\n<li>Binder<\/li>\n\n\n\n<li>Seal Agent<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Alkaline Batteries 9V<\/h2>\n\n\n\n<ul class=\"u-mb-ctrl u-mb-20 wp-block-list\">\n<li>Zinc Powder<\/li>\n\n\n\n<li>Stainless Steel Strip<\/li>\n\n\n\n<li>Nickel Plated Steel Strip<\/li>\n\n\n\n<li>Binder<\/li>\n\n\n\n<li>Separator<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Alkaline Button Cells<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Separator<\/li>\n\n\n\n<li>Carbon Steel Strip<\/li>\n\n\n\n<li>Nickel Plated Steel Strip<\/li>\n\n\n\n<li>Gasket<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"swell-block-fullWide pc-py-20 sp-py-20 alignfull c5-ft-container\"><div class=\"swell-block-fullWide__inner\">\n<div class=\"swell-block-columns bbox\" style=\"--swl-clmn-mrgn--x:2rem\"><div class=\"swell-block-columns__inner\">\n<div class=\"swell-block-column swl-has-mb--s col\" style=\"--clmn-w--pc:30%\">\n<figure class=\"wp-block-image size-full c5-img u-lb-off u-mb-ctrl u-mb-20\"><img decoding=\"async\" width=\"340\" height=\"193\" src=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/silver_oxide_button_cell.png\" alt=\"\" class=\"wp-image-1452\" srcset=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/silver_oxide_button_cell.png 340w, https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/04\/silver_oxide_button_cell-300x170.png 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/figure>\n\n\n\n<p class=\"cap1\">Silver Oxide Button Cell<\/p>\n\n\n\n<p class=\"cap2\">Data from &#8216;Battery Association of Japan&#8217;<\/p>\n<\/div>\n\n\n\n<div class=\"swell-block-column swl-has-mb--s col\" style=\"--clmn-w--pc:70%\">\n<div class=\"wp-block-group is-stack c5-text\">\n<h2 class=\"wp-block-heading\">Silver Oxide Button Cell<\/h2>\n\n\n\n<ul class=\"u-mb-ctrl u-mb-20 wp-block-list\">\n<li>Separator<\/li>\n\n\n\n<li>Carbon Steel Strip<\/li>\n\n\n\n<li>Gasket<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"swell-block-fullWide pc-py-20 sp-py-20 alignfull c5-ft-container\"><div class=\"swell-block-fullWide__inner\">\n<div class=\"swell-block-columns bbox\" style=\"--swl-clmn-mrgn--x:2rem\"><div class=\"swell-block-columns__inner\">\n<div class=\"swell-block-column swl-has-mb--s col-lb\" style=\"--clmn-w--pc:30%\">\n<figure class=\"wp-block-image size-full c5-img u-lb-off u-mb-ctrl u-mb-20\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/03\/IMG.png\" alt=\"\" class=\"wp-image-127\" srcset=\"https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/03\/IMG.png 1920w, https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/03\/IMG-300x169.png 300w, https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/03\/IMG-1024x576.png 1024w, https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/03\/IMG-768x432.png 768w, https:\/\/e-kanagawa.co.jp\/en\/wp-content\/uploads\/2024\/03\/IMG-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"cap1\">Lithium Battery<\/p>\n\n\n\n<p class=\"cap2\">Data from &#8216;Battery Association of Japan&#8217;<\/p>\n<\/div>\n\n\n\n<div class=\"swell-block-column swl-has-mb--s col\" style=\"--clmn-w--pc:70%\">\n<div class=\"wp-block-group is-stack c5-text\">\n<h2 class=\"wp-block-heading\">Lithium Batteries (Coin cells &amp; Cylindrical cells)<\/h2>\n\n\n\n<ul class=\"u-mb-ctrl u-mb-20 wp-block-list\">\n<li>Separator<\/li>\n\n\n\n<li>Gasket(PP, NYLON, PFA, PEEK)<\/li>\n\n\n\n<li>Stainless Steel Cans<\/li>\n\n\n\n<li>Hermetic Seal<\/li>\n\n\n\n<li>Silver Oxide Powder<\/li>\n\n\n\n<li>Zinc Powder<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-right\"><span class=\"swl-fz u-fz-s\">\u203bSource of the structual drawings: Battery Association of Japan<\/span><\/p>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"swell_btn_cv_data":"","footnotes":""},"class_list":["post-258","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/pages\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/comments?post=258"}],"version-history":[{"count":1,"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/pages\/258\/revisions"}],"predecessor-version":[{"id":1548,"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/pages\/258\/revisions\/1548"}],"wp:attachment":[{"href":"https:\/\/e-kanagawa.co.jp\/en\/wp-json\/wp\/v2\/media?parent=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}